{"id":18346,"date":"2023-02-27T20:26:19","date_gmt":"2023-02-27T09:26:19","guid":{"rendered":"https:\/\/www.mediacp.net\/nao-categorizado\/mediacp-2-11-copia-agora-disponivel\/"},"modified":"2023-02-27T20:35:33","modified_gmt":"2023-02-27T09:35:33","slug":"mediacp-2-11-copia-agora-disponivel","status":"publish","type":"post","link":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/","title":{"rendered":"Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18346\" class=\"elementor elementor-18346 elementor-18343\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffd4a0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffd4a0a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5311081\" data-id=\"5311081\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2c6bc9 elementor-widget elementor-widget-text-editor\" data-id=\"d2c6bc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">O Painel de Controle de M\u00eddia inclui recursos abrangentes para operar uma esta\u00e7\u00e3o de r\u00e1dio com SHOUTcast ou Icecast, incluindo vis\u00e3o geral do servi\u00e7o central atualizado em tempo real, interfaces amig\u00e1veis e poderosos recursos AutoDJ com relat\u00f3rios de desempenho para atender \u00e0s obriga\u00e7\u00f5es de suas esta\u00e7\u00f5es.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-005f2d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"005f2d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c5ce28\" data-id=\"8c5ce28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c32134 elementor-widget elementor-widget-heading\" data-id=\"2c32134\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">O que h\u00e1 de novo em 2.11?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-700f238 uael-aspect-ratio-16_9 uael-youtube-subscribe-no elementor-widget elementor-widget-uael-video\" data-id=\"700f238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__outer-wrap  uael-video-type-youtube\" data-device=\"false\" data-vsticky=\"no\" data-hidedesktop=\"\" data-hidetablet=\"\" data-hidemobile=\"\" data-vsticky-viewport=\"0\" data-autoplay=\"0\">\n\t\t\t\t\t\t<div class=\"uael-video-inner-wrap\">\n\t\t\t\t<div class=\"uael-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/9hBfN-13wjE?rel=0&amp;start&amp;end&amp;controls=1&amp;mute=0&amp;modestbranding=1&amp;\">\n\t\t\t\t\t<img decoding=\"async\" class=\"uael-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/9hBfN-13wjE\/maxresdefault.jpg\" alt=\"\"><\/img>\n\t\t\t\t\t<div class=\"uael-video__play-icon uael-animation-\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa fa-play-circle\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4f74a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4f74a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-990af5d\" data-id=\"990af5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6d4421 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f6d4421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.mediacp.net\/pt-br\/avaliacao-gratuita\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Experimente gr\u00e1tis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc187b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc187b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b5720a\" data-id=\"5b5720a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d81416 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"8d81416\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-broadcast-tower\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df010a4 elementor-widget elementor-widget-heading\" data-id=\"df010a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vis\u00e3o geral do servi\u00e7o de \u00e1udio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-888438c elementor-widget elementor-widget-text-editor\" data-id=\"888438c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">A vis\u00e3o geral de servi\u00e7o para os servi\u00e7os SHOUTcast e Icecast agora \u00e9 completamente revisada com uma vis\u00e3o geral da esta\u00e7\u00e3o atualizada dinamicamente. Adicionamos um componente Rec\u00e9m-Jogado e substitu\u00edmos o Google Maps.  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06d445d elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06d445d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3726c9\" data-id=\"e3726c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e1e371 elementor-widget elementor-widget-image\" data-id=\"5e1e371\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1338\" height=\"720\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif\" class=\"attachment-1536x1536 size-1536x1536 wp-image-12599\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7ff1d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7ff1d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12684c4\" data-id=\"12684c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7534098 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"7534098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-music\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8efba42 elementor-widget elementor-widget-heading\" data-id=\"8efba42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gerenciamento de faixas de m\u00eddia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4217777 elementor-widget elementor-widget-text-editor\" data-id=\"4217777\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-align: left;\">Arraste e solte m\u00eddia do seu desktop, em seguida, edite os meta dados e cubra diretamente da nossa nova interface moderna.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-222f3f1 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"222f3f1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c9af8b1\" data-id=\"c9af8b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4490cb elementor-widget elementor-widget-image\" data-id=\"a4490cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/media_manager_v211.gif\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"media_manager_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI1OTQsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9tZWRpYV9tYW5hZ2VyX3YyMTEuZ2lmIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1338\" height=\"720\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/media_manager_v211.gif\" class=\"attachment-1536x1536 size-1536x1536 wp-image-12594\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c6435c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c6435c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c7da73\" data-id=\"5c7da73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64e8dec elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"64e8dec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-list-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb11f50 elementor-widget elementor-widget-heading\" data-id=\"bb11f50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Listas de reprodu\u00e7\u00e3o e faixas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bebdf6c elementor-widget elementor-widget-text-editor\" data-id=\"bebdf6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-align: left;\">Gerenciar suas listas de reprodu\u00e7\u00e3o agora \u00e9 mais f\u00e1cil do que sempre com o nosso construtor de playlists moderno, agora voc\u00ea pode construir suas listas de reprodu\u00e7\u00e3o arrastando e soltando pastas inteiras, \u00e1lbuns, artistas ou faixas individuais.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a20409e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a20409e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9b06dd1\" data-id=\"9b06dd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e72fc02 elementor-widget elementor-widget-image\" data-id=\"e72fc02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/playlist_tracks_v211.gif\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"playlist_tracks_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2MDcsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9wbGF5bGlzdF90cmFja3NfdjIxMS5naWYifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1331\" height=\"720\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/playlist_tracks_v211.gif\" class=\"attachment-1536x1536 size-1536x1536 wp-image-12607\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-409e4cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"409e4cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f93014\" data-id=\"7f93014\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a34547 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"1a34547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-bell\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f530b12 elementor-widget elementor-widget-heading\" data-id=\"f530b12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Jingles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f366ee3 elementor-widget elementor-widget-text-editor\" data-id=\"f366ee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-align: left;\">As playlists jingles podem ser configuradas em 3 estilos de reprodu\u00e7\u00e3o diferentes, por faixas, minutos ou de hora em hora no minuto. Jingles podem ser configurados para tocar em um hor\u00e1rio espec\u00edfico, ou intervalo, e at\u00e9 mesmo interumem a faixa atualmente.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1819e29 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1819e29\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-816a0fa\" data-id=\"816a0fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d2860c elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"4d2860c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4d2860c\" data-elementor-lightbox-title=\"jingles_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2MTIsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9qaW5nbGVzX3YyMTEucG5nIiwic2xpZGVzaG93IjoiNGQyODYwYyJ9\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/jingles_v211.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/jingles_v211-1024x550.png\" alt=\"jingles_v211\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4d2860c\" data-elementor-lightbox-title=\"jingles_ads_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2MTcsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9qaW5nbGVzX2Fkc192MjExLnBuZyIsInNsaWRlc2hvdyI6IjRkMjg2MGMifQ%3D%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/jingles_ads_v211.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/jingles_ads_v211-1024x550.png\" alt=\"jingles_ads_v211\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4d2860c\" data-elementor-lightbox-title=\"jingles_hourly_sweepers\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2MjIsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9qaW5nbGVzX2hvdXJseV9zd2VlcGVycy5wbmciLCJzbGlkZXNob3ciOiI0ZDI4NjBjIn0%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/jingles_hourly_sweepers.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/jingles_hourly_sweepers-1024x550.png\" alt=\"jingles_hourly_sweepers\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da9737b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da9737b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-195e654\" data-id=\"195e654\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-035274e elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"035274e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-658aacf elementor-widget elementor-widget-heading\" data-id=\"658aacf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hor\u00e1rios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b30925 elementor-widget elementor-widget-text-editor\" data-id=\"4b30925\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-align: left;\">Um calend\u00e1rio de agendamento j\u00e1 est\u00e1 dispon\u00edvel para planejar a transmiss\u00e3o de suas esta\u00e7\u00f5es, com op\u00e7\u00f5es recorrentes abrangentes. Os programas podem at\u00e9 ser programados para come\u00e7ar exatamente em um momento espec\u00edfico e interromper qualquer conte\u00fado existente.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cceae7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cceae7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d45880\" data-id=\"2d45880\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85e99bc elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"85e99bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"85e99bc\" data-elementor-lightbox-title=\"hor\u00e1rio\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2MzAsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9zY2hlZHVsZS5wbmciLCJzbGlkZXNob3ciOiI4NWU5OWJjIn0%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/schedule.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/schedule-1024x550.png\" alt=\"hor\u00e1rio\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"85e99bc\" data-elementor-lightbox-title=\"schedule_daily\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2MzUsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9zY2hlZHVsZV9kYWlseS5wbmciLCJzbGlkZXNob3ciOiI4NWU5OWJjIn0%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/schedule_daily.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/schedule_daily-1024x550.png\" alt=\"schedule_daily\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"85e99bc\" data-elementor-lightbox-title=\"schedule_first_monday_monthly\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2NDAsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9zY2hlZHVsZV9maXJzdF9tb25kYXlfbW9udGhseS5wbmciLCJzbGlkZXNob3ciOiI4NWU5OWJjIn0%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/schedule_first_monday_monthly.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/schedule_first_monday_monthly-1024x550.png\" alt=\"schedule_first_monday_monthly\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d657527 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d657527\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6b627f\" data-id=\"b6b627f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a610a18 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"a610a18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-save\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da52819 elementor-widget elementor-widget-heading\" data-id=\"da52819\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Grava\u00e7\u00e3o de transmiss\u00e3o ao vivo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-700b261 elementor-widget elementor-widget-text-editor\" data-id=\"700b261\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-align: left;\">Transmiss\u00f5es ao vivo transmitidas pela plataforma AutoDJ podem ser gravadas automaticamente em uma estrutura de pastas representando o ano, m\u00eas e dia.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98dd51c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98dd51c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4ba7fc\" data-id=\"d4ba7fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cadc50b elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"cadc50b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9a23d4 elementor-widget elementor-widget-heading\" data-id=\"b9a23d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Widgets<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b72d89 elementor-widget elementor-widget-text-editor\" data-id=\"3b72d89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-align: left;\">URLs de servi\u00e7o importantes, bem como o c\u00f3digo de incorpora\u00e7\u00e3o do leitor de \u00e1udio est\u00e3o agora inclu\u00eddos em uma nova guia Your Station de Widgets &amp; Links. V\u00e1rios novos widgets est\u00e3o agora dispon\u00edveis e os widgets existentes foram melhorados.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9b9d3b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9b9d3b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-778ac8e\" data-id=\"778ac8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41e9ebf elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"41e9ebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"41e9ebf\" data-elementor-lightbox-title=\"widget_your_station\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2NDgsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC93aWRnZXRfeW91cl9zdGF0aW9uLmpwZyIsInNsaWRlc2hvdyI6IjQxZTllYmYifQ%3D%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/widget_your_station.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/widget_your_station-1024x550.jpg\" alt=\"widget_your_station\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"41e9ebf\" data-elementor-lightbox-title=\"widget_now_playing\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2NTMsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC93aWRnZXRfbm93X3BsYXlpbmcuanBnIiwic2xpZGVzaG93IjoiNDFlOWViZiJ9\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/widget_now_playing.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/widget_now_playing-1024x550.jpg\" alt=\"widget_now_playing\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"41e9ebf\" data-elementor-lightbox-title=\"widget_recent_upcoming\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2NTgsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC93aWRnZXRfcmVjZW50X3VwY29taW5nLnBuZyIsInNsaWRlc2hvdyI6IjQxZTllYmYifQ%3D%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/widget_recent_upcoming.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/widget_recent_upcoming-1024x550.png\" alt=\"widget_recent_upcoming\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"41e9ebf\" data-elementor-lightbox-title=\"widget_weekly_google_maps\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2NjMsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC93aWRnZXRfd2Vla2x5X2dvb2dsZV9tYXBzLnBuZyIsInNsaWRlc2hvdyI6IjQxZTllYmYifQ%3D%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/widget_weekly_google_maps.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/widget_weekly_google_maps-1024x550.png\" alt=\"widget_weekly_google_maps\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cae05dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cae05dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d251023\" data-id=\"d251023\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a430de elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"5a430de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69ae93c elementor-widget elementor-widget-heading\" data-id=\"69ae93c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Desempenho &amp; Reprodu\u00e7\u00e3o\nRelat\u00f3rios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16c30a4 elementor-widget elementor-widget-text-editor\" data-id=\"16c30a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-align: left;\">Dois novos relat\u00f3rios foram adicionados que fornecem informa\u00e7\u00f5es de acordo com os requisitos de relat\u00f3rios reais.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d74eec elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d74eec\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d3fdc6\" data-id=\"4d3fdc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edfd476 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"edfd476\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"edfd476\" data-elementor-lightbox-title=\"performances_report_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2NzEsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9wZXJmb3JtYW5jZXNfcmVwb3J0X3YyMTEucG5nIiwic2xpZGVzaG93IjoiZWRmZDQ3NiJ9\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/performances_report_v211.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/performances_report_v211.png\" alt=\"performances_report_v211\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"edfd476\" data-elementor-lightbox-title=\"playback_report_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2NzYsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9wbGF5YmFja19yZXBvcnRfdjIxMS5wbmciLCJzbGlkZXNob3ciOiJlZGZkNDc2In0%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/playback_report_v211.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/playback_report_v211.png\" alt=\"playback_report_v211\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e80ef07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e80ef07\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06c846f\" data-id=\"06c846f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-064bcaf elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"064bcaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1358b6 elementor-widget elementor-widget-heading\" data-id=\"b1358b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Modo Escuro<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85cce46 elementor-widget elementor-widget-text-editor\" data-id=\"85cce46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-align: left;\">O modo escuro \u00e9 detectado a partir das configura\u00e7\u00f5es do dispositivo e aplicado automaticamente em todo o software. Um alternador modo escuro\/claro est\u00e1 inclu\u00eddo na parte superior da interface ao lado das op\u00e7\u00f5es de idioma e persiste no dispositivo.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd9076e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd9076e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07bba4c\" data-id=\"07bba4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ab5bb0 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"7ab5bb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 5\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ab5bb0\" data-elementor-lightbox-title=\"login_dark_mode_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2ODQsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9sb2dpbl9kYXJrX21vZGVfdjIxMS5qcGciLCJzbGlkZXNob3ciOiI3YWI1YmIwIn0%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/login_dark_mode_v211.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/login_dark_mode_v211-1024x550.jpg\" alt=\"login_dark_mode_v211\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 5\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ab5bb0\" data-elementor-lightbox-title=\"dashboard_dark_mode_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2ODksInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9kYXNoYm9hcmRfZGFya19tb2RlX3YyMTEuanBnIiwic2xpZGVzaG93IjoiN2FiNWJiMCJ9\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/dashboard_dark_mode_v211.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/dashboard_dark_mode_v211-1024x550.jpg\" alt=\"dashboard_dark_mode_v211\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 5\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ab5bb0\" data-elementor-lightbox-title=\"services_dark_mode_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2OTQsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9zZXJ2aWNlc19kYXJrX21vZGVfdjIxMS5wbmciLCJzbGlkZXNob3ciOiI3YWI1YmIwIn0%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/services_dark_mode_v211.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/services_dark_mode_v211-1024x550.png\" alt=\"services_dark_mode_v211\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 5\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ab5bb0\" data-elementor-lightbox-title=\"service_overview_dark_mode_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2OTksInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9zZXJ2aWNlX292ZXJ2aWV3X2RhcmtfbW9kZV92MjExLnBuZyIsInNsaWRlc2hvdyI6IjdhYjViYjAifQ%3D%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_dark_mode_v211.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_dark_mode_v211-1024x550.png\" alt=\"service_overview_dark_mode_v211\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 5\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ab5bb0\" data-elementor-lightbox-title=\"media_dark_mode_v211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI3MDQsInVybCI6Imh0dHBzOlwvXC93d3cubWVkaWFjcC5uZXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzEwXC9tZWRpYV9kYXJrX21vZGVfdjIxMS5wbmciLCJzbGlkZXNob3ciOiI3YWI1YmIwIn0%3D\" href=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/media_dark_mode_v211.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/media_dark_mode_v211-1024x550.png\" alt=\"media_dark_mode_v211\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ce2665 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ce2665\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9a5c58\" data-id=\"f9a5c58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc2cdd5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"dc2cdd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.mediacp.net\/pt-br\/avaliacao-gratuita\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Experimente gr\u00e1tis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3afda8a8 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"3afda8a8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31482a2e\" data-id=\"31482a2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14d2151f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"14d2151f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.mediacp.net\/pt-br\/notas-de-lancamento\/notas-de-versao-do-mediacp-2-11-7\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Exibir notas de lan\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>O MediaCP 2.11 inclui grandes melhorias em quase todos os aspectos dos servi\u00e7os SHOUTcast &amp; Icecast com uma nova p\u00e1gina de Vis\u00e3o geral do servi\u00e7o, gerenciamento revisado de faixas de m\u00eddia e recursos autoDJ.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[364],"tags":[450,447,448,449],"class_list":["post-18346","post","type-post","status-publish","format-standard","hentry","category-blogue","tag-audio-pt-br","tag-radio-pt-br","tag-estacao","tag-caracteristicas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio - MediaCP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio - MediaCP\" \/>\n<meta property=\"og:description\" content=\"O MediaCP 2.11 inclui grandes melhorias em quase todos os aspectos dos servi\u00e7os SHOUTcast &amp; Icecast com uma nova p\u00e1gina de Vis\u00e3o geral do servi\u00e7o, gerenciamento revisado de faixas de m\u00eddia e recursos autoDJ.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/\" \/>\n<meta property=\"og:site_name\" content=\"MediaCP\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-27T09:26:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T09:35:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif\" \/>\n<meta name=\"author\" content=\"Matt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/\"},\"author\":{\"name\":\"Matt\",\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/#\/schema\/person\/52076efd15323f23821aba893c22c6de\"},\"headline\":\"Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio\",\"datePublished\":\"2023-02-27T09:26:19+00:00\",\"dateModified\":\"2023-02-27T09:35:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/\"},\"wordCount\":455,\"publisher\":{\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif\",\"keywords\":[\"\u00e1udio\",\"radio\",\"esta\u00e7\u00e3o\",\"Caracter\u00edsticas\"],\"articleSection\":[\"Blogue\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/\",\"url\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/\",\"name\":\"Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio - MediaCP\",\"isPartOf\":{\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif\",\"datePublished\":\"2023-02-27T09:26:19+00:00\",\"dateModified\":\"2023-02-27T09:35:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#primaryimage\",\"url\":\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif\",\"contentUrl\":\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mediacp.net\/pt-br\/mediacp-painel-de-controle-de-radio-e-video-shoutcast-icecast-motor-de-streaming-wowza-video-em-nuvem\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/#website\",\"url\":\"https:\/\/www.mediacp.net\/pt-br\/\",\"name\":\"MediaCP\",\"description\":\"Media Control Panel\",\"publisher\":{\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mediacp.net\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/#organization\",\"name\":\"Media Control Panel\",\"url\":\"https:\/\/www.mediacp.net\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2016\/09\/logo-1.png\",\"contentUrl\":\"https:\/\/www.mediacp.net\/wp-content\/uploads\/2016\/09\/logo-1.png\",\"width\":460,\"height\":116,\"caption\":\"Media Control Panel\"},\"image\":{\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/#\/schema\/person\/52076efd15323f23821aba893c22c6de\",\"name\":\"Matt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.mediacp.net\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/933f1ca462b6ab59b4fb5dc5f6e026471435e7e28029efd010e3906b8981fe41?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/933f1ca462b6ab59b4fb5dc5f6e026471435e7e28029efd010e3906b8981fe41?s=96&d=mm&r=g\",\"caption\":\"Matt\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio - MediaCP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/","og_locale":"pt_BR","og_type":"article","og_title":"Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio - MediaCP","og_description":"O MediaCP 2.11 inclui grandes melhorias em quase todos os aspectos dos servi\u00e7os SHOUTcast &amp; Icecast com uma nova p\u00e1gina de Vis\u00e3o geral do servi\u00e7o, gerenciamento revisado de faixas de m\u00eddia e recursos autoDJ.","og_url":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/","og_site_name":"MediaCP","article_published_time":"2023-02-27T09:26:19+00:00","article_modified_time":"2023-02-27T09:35:33+00:00","og_image":[{"url":"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif","type":"","width":"","height":""}],"author":"Matt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Matt","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#article","isPartOf":{"@id":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/"},"author":{"name":"Matt","@id":"https:\/\/www.mediacp.net\/pt-br\/#\/schema\/person\/52076efd15323f23821aba893c22c6de"},"headline":"Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio","datePublished":"2023-02-27T09:26:19+00:00","dateModified":"2023-02-27T09:35:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/"},"wordCount":455,"publisher":{"@id":"https:\/\/www.mediacp.net\/pt-br\/#organization"},"image":{"@id":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif","keywords":["\u00e1udio","radio","esta\u00e7\u00e3o","Caracter\u00edsticas"],"articleSection":["Blogue"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/","url":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/","name":"Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio - MediaCP","isPartOf":{"@id":"https:\/\/www.mediacp.net\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#primaryimage"},"image":{"@id":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif","datePublished":"2023-02-27T09:26:19+00:00","dateModified":"2023-02-27T09:35:33+00:00","breadcrumb":{"@id":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#primaryimage","url":"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif","contentUrl":"https:\/\/www.mediacp.net\/wp-content\/uploads\/2021\/10\/service_overview_211.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mediacp.net\/pt-br\/blogue\/mediacp-2-11-copia-agora-disponivel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mediacp.net\/pt-br\/mediacp-painel-de-controle-de-radio-e-video-shoutcast-icecast-motor-de-streaming-wowza-video-em-nuvem\/"},{"@type":"ListItem","position":2,"name":"Caracter\u00edsticas para esta\u00e7\u00f5es de r\u00e1dio"}]},{"@type":"WebSite","@id":"https:\/\/www.mediacp.net\/pt-br\/#website","url":"https:\/\/www.mediacp.net\/pt-br\/","name":"MediaCP","description":"Media Control Panel","publisher":{"@id":"https:\/\/www.mediacp.net\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mediacp.net\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.mediacp.net\/pt-br\/#organization","name":"Media Control Panel","url":"https:\/\/www.mediacp.net\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mediacp.net\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.mediacp.net\/wp-content\/uploads\/2016\/09\/logo-1.png","contentUrl":"https:\/\/www.mediacp.net\/wp-content\/uploads\/2016\/09\/logo-1.png","width":460,"height":116,"caption":"Media Control Panel"},"image":{"@id":"https:\/\/www.mediacp.net\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mediacp.net\/pt-br\/#\/schema\/person\/52076efd15323f23821aba893c22c6de","name":"Matt","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mediacp.net\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/933f1ca462b6ab59b4fb5dc5f6e026471435e7e28029efd010e3906b8981fe41?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/933f1ca462b6ab59b4fb5dc5f6e026471435e7e28029efd010e3906b8981fe41?s=96&d=mm&r=g","caption":"Matt"}}]}},"_links":{"self":[{"href":"https:\/\/www.mediacp.net\/pt-br\/wp-json\/wp\/v2\/posts\/18346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mediacp.net\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mediacp.net\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mediacp.net\/pt-br\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mediacp.net\/pt-br\/wp-json\/wp\/v2\/comments?post=18346"}],"version-history":[{"count":0,"href":"https:\/\/www.mediacp.net\/pt-br\/wp-json\/wp\/v2\/posts\/18346\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mediacp.net\/pt-br\/wp-json\/wp\/v2\/media?parent=18346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mediacp.net\/pt-br\/wp-json\/wp\/v2\/categories?post=18346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mediacp.net\/pt-br\/wp-json\/wp\/v2\/tags?post=18346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}